{"id":19578,"date":"2023-04-20T13:40:54","date_gmt":"2023-04-20T11:40:54","guid":{"rendered":"https:\/\/www.reseau-mesure.com\/?p=19578"},"modified":"2023-04-20T13:44:46","modified_gmt":"2023-04-20T11:44:46","slug":"nouveaute-chez-jm-concept","status":"publish","type":"post","link":"https:\/\/www.reseau-mesure.com\/de\/nouveaute-chez-jm-concept\/","title":{"rendered":"Neu bei JM Concept f\u00fcr Gauge Bridge- oder Wheatstone-Eintr\u00e4ge auf dem Markt f\u00fcr Industriehebetechnik"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p style=\"background: white;\"><strong><span style=\"font-family: 'Segoe UI',sans-serif; color: #172b4d; letter-spacing: -.05pt;\">Neu bei JM Concept: der XALIS 1000SIL<\/span><\/strong><\/p>\n<p style=\"background: white;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #172b4d; letter-spacing: -.05pt;\"><a href=\"https:\/\/www.reseau-mesure.com\/de\/adherent\/jm-concept\/\">JM-Konzept<\/a> bringt sein brandneues Produkt, den XALIS 1000SIL, auf den Markt, der Teil seiner Reihe von XALIS 1000-Indikatoren ist, die speziell f\u00fcr Spurbr\u00fccken- oder Wheatstone-Eing\u00e4nge im industriellen Hebemarkt entwickelt wurden. Als Reaktion auf die wachsende Nachfrage seiner Kunden zeichnet sich diese neueste Erg\u00e4nzung der Produktreihe durch ihren SIL2-zertifizierten Sicherheitsmodus aus.<\/span><\/p>\n<p style=\"background: white;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #172b4d; letter-spacing: -.05pt;\">Das XALIS 1000SIL bietet als einziges Ger\u00e4t auf dem Markt folgende Eigenschaften: SIL 2-Zertifizierung f\u00fcr 4- bis 6-adrige Br\u00fcckeneing\u00e4nge, zwei analoge Ausg\u00e4nge, davon einer SIL 2-zertifiziert, 1 bis 4 ebenfalls SIL 2-zertifizierte Relaisausg\u00e4nge, und Kommunikation \u00fcber den Feldbus Modbus RTU. Diese Kombination von Merkmalen macht es zur idealen Wahl f\u00fcr industrielle Hebeanwendungen, die ein hohes Ma\u00df an Zuverl\u00e4ssigkeit und Sicherheit f\u00fcr \u00dcberwachungs- und Steuerungssysteme erfordern.<a href=\"https:\/\/jmconcept.com\/fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\" alt=\"\" width=\"286\" height=\"400\" \/> <\/a><\/span><\/p>\n<p style=\"background: white; text-align: justify;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #172b4d; letter-spacing: -.05pt;\">Im Hinblick auf seine Sicherheitsfunktionen gem\u00e4\u00df der Norm IEC 61508-2 ist der XALIS 1000SIL in der Lage, ein Spannungs- oder Stromausgangssignal zu erzeugen, das repr\u00e4sentativ f\u00fcr eine Messbr\u00fcckeneingangsgr\u00f6\u00dfe ist. Es kann auch die Relaisausg\u00e4nge in eine Fallback-Position schalten, wenn eine vom Bediener definierte Schwelle \u00fcberschritten wird. Dar\u00fcber hinaus werden im Fall eines erkannten Fehlers Fallback-Modi oder sichere Zust\u00e4nde an den Analog- und Relaisausg\u00e4ngen definiert, wodurch eine erh\u00f6hte Sicherheit im Hebebetrieb gew\u00e4hrleistet wird.<\/span><\/p>\n<p style=\"background: white; text-align: justify;\"><span style=\"font-family: 'Segoe UI',sans-serif; color: #172b4d; letter-spacing: -.05pt;\">Der XALIS 1000SIL bietet auch die gleichen Vorteile, die f\u00fcr JM Concept-Ger\u00e4te spezifisch sind, insbesondere ihre Universalit\u00e4t, ihre Isolierung, ihre Ausziehbarkeit und ihre Kommunikation. Die Zuverl\u00e4ssigkeit dieses neuen Produkts ist vergleichbar mit der der anderen Ger\u00e4te der Marke, da sie alle strengen Unit-Tests unterzogen werden, wodurch JM Concept seinen Kunden eine 5-Jahres-Garantie gew\u00e4hren kann.<\/span><\/p>\n<p>\u00a0<\/p>\n<p>https:\/\/jmconcept.com\/<\/p>\n<p><a href=\"https:\/\/jmconcept.com\/fr\/\"><img decoding=\"async\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2021\/07\/Logo-JM-Concept.jpg\" alt=\"\" \/><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Neu bei JM Concept: der XALIS 1000SIL JM Concept bringt sein brandneues Produkt, den XALIS 1000SIL, auf den Markt, der Teil seiner XALIS 1000-Anzeigenreihe ist, die speziell f\u00fcr Spurbr\u00fccken- oder Wheatstone-Eing\u00e4nge im industriellen Hebemarkt entwickelt wurde. Dieser Neuzugang im Sortiment zeichnet sich durch seinen Sicherheitsmodus aus\u2026<\/p>","protected":false},"author":349,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19578","post","type-post","status-publish","format-standard","hentry","category-defaut"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure<\/title>\n<meta name=\"description\" content=\"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reseau-mesure.com\/de\/nouveaute-chez-jm-concept\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure\" \/>\n<meta property=\"og:description\" content=\"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reseau-mesure.com\/de\/nouveaute-chez-jm-concept\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau Mesure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/reseaumesure\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T11:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T11:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\" \/>\n<meta name=\"author\" content=\"Claire Onfray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:site\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claire Onfray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/\"},\"author\":{\"name\":\"Claire Onfray\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/007ab9dfe1368385ff2e9d190ad34081\"},\"headline\":\"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel\",\"datePublished\":\"2023-04-20T11:40:54+00:00\",\"dateModified\":\"2023-04-20T11:44:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\",\"articleSection\":[\"Defaut\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/\",\"name\":\"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\",\"datePublished\":\"2023-04-20T11:40:54+00:00\",\"dateModified\":\"2023-04-20T11:44:46+00:00\",\"description\":\"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/nouveaute-chez-jm-concept\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"name\":\"R\u00e9seau-Mesure\",\"description\":\"R\u00e9seau Mesure\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reseau-mesure.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\",\"name\":\"R\u00e9seau-Mesure\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"width\":545,\"height\":285,\"caption\":\"R\u00e9seau-Mesure\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/reseaumesure\\\/\",\"https:\\\/\\\/x.com\\\/ReseauMesure\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reseau-mesure\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/007ab9dfe1368385ff2e9d190ad34081\",\"name\":\"Claire Onfray\",\"sameAs\":[\"https:\\\/\\\/www.reseau-mesure.com\"],\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/de\\\/author\\\/confrayreseau-mesure-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure","description":"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reseau-mesure.com\/de\/nouveaute-chez-jm-concept\/","og_locale":"de_DE","og_type":"article","og_title":"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure","og_description":"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission","og_url":"https:\/\/www.reseau-mesure.com\/de\/nouveaute-chez-jm-concept\/","og_site_name":"R\u00e9seau Mesure","article_publisher":"https:\/\/www.facebook.com\/reseaumesure\/","article_published_time":"2023-04-20T11:40:54+00:00","article_modified_time":"2023-04-20T11:44:46+00:00","og_image":[{"url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg","type":"","width":"","height":""}],"author":"Claire Onfray","twitter_card":"summary_large_image","twitter_creator":"@ReseauMesure","twitter_site":"@ReseauMesure","twitter_misc":{"Verfasst von":"Claire Onfray","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#article","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/"},"author":{"name":"Claire Onfray","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/007ab9dfe1368385ff2e9d190ad34081"},"headline":"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel","datePublished":"2023-04-20T11:40:54+00:00","dateModified":"2023-04-20T11:44:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/"},"wordCount":358,"publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg","articleSection":["Defaut"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/","url":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/","name":"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel - R\u00e9seau Mesure","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#primaryimage"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg","datePublished":"2023-04-20T11:40:54+00:00","dateModified":"2023-04-20T11:44:46+00:00","description":"JM Concept fabrique et commercialise des conditionneurs de signaux de haute pr\u00e9cision permettant la mesure, la conversion, la transmission","breadcrumb":{"@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#primaryimage","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/04\/JM-CONCEPT-Visuel-XALIS-SIL_HD.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reseau-mesure.com\/nouveaute-chez-jm-concept\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.reseau-mesure.com\/"},{"@type":"ListItem","position":2,"name":"Nouveaut\u00e9 chez JM Concept pour les entr\u00e9es Pont de Jauge ou Wheatstone dans le march\u00e9 du Levage Industriel"}]},{"@type":"WebSite","@id":"https:\/\/www.reseau-mesure.com\/#website","url":"https:\/\/www.reseau-mesure.com\/","name":"Netzwerk-Messung","description":"Netzwerkma\u00dfnahme","publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reseau-mesure.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.reseau-mesure.com\/#organization","name":"Netzwerk-Messung","url":"https:\/\/www.reseau-mesure.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","width":545,"height":285,"caption":"R\u00e9seau-Mesure"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/reseaumesure\/","https:\/\/x.com\/ReseauMesure","https:\/\/www.linkedin.com\/company\/reseau-mesure\/"]},{"@type":"Person","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/007ab9dfe1368385ff2e9d190ad34081","name":"Claire Onfray","sameAs":["https:\/\/www.reseau-mesure.com"],"url":"https:\/\/www.reseau-mesure.com\/de\/author\/confrayreseau-mesure-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts\/19578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/comments?post=19578"}],"version-history":[{"count":0,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts\/19578\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/media?parent=19578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/categories?post=19578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/tags?post=19578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}