{"id":22167,"date":"2024-04-23T10:29:06","date_gmt":"2024-04-23T08:29:06","guid":{"rendered":"https:\/\/www.reseau-mesure.com\/?p=22167"},"modified":"2024-04-23T10:29:09","modified_gmt":"2024-04-23T08:29:09","slug":"ausyris-est-fier-dannoncer-son-partenariat-avec-vention","status":"publish","type":"post","link":"https:\/\/www.reseau-mesure.com\/de\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/","title":{"rendered":"AUSYRIS est fier d&rsquo;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&rsquo;automatisation."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png\" alt=\"ausyris\" width=\"637\" height=\"242\" \/><\/p>\n<p>Gr\u00e2ce \u00e0 ce partenariat, Ausyris fusionne son expertise en ing\u00e9nierie avec les capacit\u00e9s de pointe de Vention. Ils deviennent donc int\u00e9grateurs europ\u00e9ens et particuli\u00e8rement fran\u00e7ais des syst\u00e8mes Vention, ce qui leur permet de travailler \u00e9troitement sur des solutions avanc\u00e9es int\u00e9grant des cobots et des syst\u00e8mes de profil\u00e9s de grandes envergures.<\/p>\n<p>Voici un aper\u00e7u des deux projets issus de cette toute nouvelle collaboration :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-1.png\" alt=\"\" width=\"733\" height=\"418\" \/><\/p>\n<p><strong>Projet 1\ufe0f\u20e3\u00a0\u00a0Station de travail s\u00e9curis\u00e9e pour l&rsquo;\u00e9lectronique de puissance<\/strong><\/p>\n<p>Cette station de travail s\u00e9curis\u00e9e peut \u00eatre d\u00e9di\u00e9e \u00e0 des \u00e9tudes et des essais en \u00e9lectronique de puissance. Ce premier design inclut des alimentations \u00e9lectriques et un syst\u00e8me de refroidissement liquide, con\u00e7u pour s&rsquo;int\u00e9grer \u00e0 un banc d&rsquo;essai Power HIL. Gr\u00e2ce \u00e0 son design modulaire, nous pouvons facilement \u00e9tendre ses fonctionnalit\u00e9s !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-2.png\" alt=\"\" width=\"729\" height=\"439\" \/><\/p>\n<p>Projet 2\ufe0f\u20e3\u00a0<strong>Syst\u00e8mes de contr\u00f4le pneumatique de l&rsquo;air<\/strong><\/p>\n<p>Con\u00e7u pour les applications d&rsquo;hydrog\u00e8ne et des circuits d\u2019air comprim\u00e9, ce syst\u00e8me int\u00e8gre des capteurs de mesure de process industriels et des dispositifs de distribution haute pression. Il est adapt\u00e9 pour un contr\u00f4le pr\u00e9cis de la pression et du d\u00e9bit pour des besoins de d\u00e9ploiement rapide ou la calibration de syst\u00e8mes pneumatiques.<\/p>\n<p><strong>Si vous avez des questions\u00a0<\/strong><strong>ou souhaitez discuter de vos projets\u00a0<\/strong><strong>contactez Ausyris,<a href=\"https:\/\/www.ausyris.com\/#nous-contacter\" target=\"_blank\" rel=\"noopener\">\u00a0cliquez ici\ud83d\uddb1<\/a>\u00a0<\/strong>\u00a0<\/p>\n<p data-referenceid=\"66\">\u00a0<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce \u00e0 ce partenariat, Ausyris fusionne son expertise en ing\u00e9nierie avec les capacit\u00e9s de pointe de Vention. Ils deviennent donc int\u00e9grateurs europ\u00e9ens et particuli\u00e8rement fran\u00e7ais des syst\u00e8mes Vention, ce qui leur permet de travailler \u00e9troitement sur des solutions avanc\u00e9es int\u00e9grant des cobots et des syst\u00e8mes de profil\u00e9s de grandes envergures. Voici un aper\u00e7u des deux&hellip;<\/p>","protected":false},"author":685,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22167","post","type-post","status-publish","format-standard","hentry","category-defaut"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUSYRIS est fier d&#039;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&#039;automatisation. - R\u00e9seau Mesure<\/title>\n<meta name=\"description\" content=\"AUSYRIS est fier d&#039;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&#039;automatisation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reseau-mesure.com\/de\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUSYRIS est fier d&#039;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&#039;automatisation. - R\u00e9seau Mesure\" \/>\n<meta property=\"og:description\" content=\"AUSYRIS est fier d&#039;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&#039;automatisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reseau-mesure.com\/de\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau Mesure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/reseaumesure\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T08:29:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T08:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png\" \/>\n<meta name=\"author\" content=\"Estelle Duflot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:site\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estelle Duflot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/\"},\"author\":{\"name\":\"Estelle Duflot\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/96c47926f177341f7dad0800619e50e2\"},\"headline\":\"AUSYRIS est fier d&rsquo;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&rsquo;automatisation.\",\"datePublished\":\"2024-04-23T08:29:06+00:00\",\"dateModified\":\"2024-04-23T08:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ausyris-LOGO.png\",\"articleSection\":[\"Defaut\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/\",\"name\":\"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation. - R\u00e9seau Mesure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ausyris-LOGO.png\",\"datePublished\":\"2024-04-23T08:29:06+00:00\",\"dateModified\":\"2024-04-23T08:29:09+00:00\",\"description\":\"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ausyris-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ausyris-LOGO.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUSYRIS est fier d&rsquo;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&rsquo;automatisation.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"name\":\"R\u00e9seau-Mesure\",\"description\":\"R\u00e9seau Mesure\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reseau-mesure.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\",\"name\":\"R\u00e9seau-Mesure\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"width\":545,\"height\":285,\"caption\":\"R\u00e9seau-Mesure\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/reseaumesure\\\/\",\"https:\\\/\\\/x.com\\\/ReseauMesure\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reseau-mesure\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/96c47926f177341f7dad0800619e50e2\",\"name\":\"Estelle Duflot\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/de\\\/author\\\/eduflotreseau-mesure-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation. - R\u00e9seau Mesure","description":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reseau-mesure.com\/de\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/","og_locale":"de_DE","og_type":"article","og_title":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation. - R\u00e9seau Mesure","og_description":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation.","og_url":"https:\/\/www.reseau-mesure.com\/de\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/","og_site_name":"R\u00e9seau Mesure","article_publisher":"https:\/\/www.facebook.com\/reseaumesure\/","article_published_time":"2024-04-23T08:29:06+00:00","article_modified_time":"2024-04-23T08:29:09+00:00","og_image":[{"url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png","type":"","width":"","height":""}],"author":"Estelle Duflot","twitter_card":"summary_large_image","twitter_creator":"@ReseauMesure","twitter_site":"@ReseauMesure","twitter_misc":{"Verfasst von":"Estelle Duflot","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#article","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/"},"author":{"name":"Estelle Duflot","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/96c47926f177341f7dad0800619e50e2"},"headline":"AUSYRIS est fier d&rsquo;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&rsquo;automatisation.","datePublished":"2024-04-23T08:29:06+00:00","dateModified":"2024-04-23T08:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/"},"wordCount":252,"publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png","articleSection":["Defaut"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/","url":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/","name":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation. - R\u00e9seau Mesure","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#primaryimage"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png","datePublished":"2024-04-23T08:29:06+00:00","dateModified":"2024-04-23T08:29:09+00:00","description":"AUSYRIS est fier d'annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l'automatisation.","breadcrumb":{"@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#primaryimage","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2024\/04\/ausyris-LOGO.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reseau-mesure.com\/ausyris-est-fier-dannoncer-son-partenariat-avec-vention\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.reseau-mesure.com\/"},{"@type":"ListItem","position":2,"name":"AUSYRIS est fier d&rsquo;annoncer\u00a0son partenariat avec Vention,\u00a0une entreprise renomm\u00e9e dans le secteur de l&rsquo;automatisation."}]},{"@type":"WebSite","@id":"https:\/\/www.reseau-mesure.com\/#website","url":"https:\/\/www.reseau-mesure.com\/","name":"Netzwerk-Messung","description":"Netzwerkma\u00dfnahme","publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reseau-mesure.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.reseau-mesure.com\/#organization","name":"Netzwerk-Messung","url":"https:\/\/www.reseau-mesure.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","width":545,"height":285,"caption":"R\u00e9seau-Mesure"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/reseaumesure\/","https:\/\/x.com\/ReseauMesure","https:\/\/www.linkedin.com\/company\/reseau-mesure\/"]},{"@type":"Person","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/96c47926f177341f7dad0800619e50e2","name":"Estelle Duflot","url":"https:\/\/www.reseau-mesure.com\/de\/author\/eduflotreseau-mesure-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts\/22167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/users\/685"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/comments?post=22167"}],"version-history":[{"count":0,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/posts\/22167\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/media?parent=22167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/categories?post=22167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/de\/wp-json\/wp\/v2\/tags?post=22167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}