{"id":20427,"date":"2023-09-25T13:50:39","date_gmt":"2023-09-25T11:50:39","guid":{"rendered":"https:\/\/www.reseau-mesure.com\/?p=20427"},"modified":"2023-09-25T13:55:05","modified_gmt":"2023-09-25T11:55:05","slug":"vega-capteurs-prevision-des-crues","status":"publish","type":"post","link":"https:\/\/www.reseau-mesure.com\/en\/vega-capteurs-prevision-des-crues\/","title":{"rendered":"VEGA is developing a secure cloud and radar level sensor solution for flood forecasting."},"content":{"rendered":"<p>As the number one natural risk in France, flooding affects all regions. To anticipate flood risks, intermunicipalities as well as private sector players such as manufacturers and campsites seek to equip themselves with forecasting systems that complement state services. It&#039;s there that <a href=\"https:\/\/www.reseau-mesure.com\/en\/adherent\/vega\/\" target=\"_blank\" rel=\"noopener\">VEGA<\/a> provides an innovative, turnkey solution. It is made up of sensors which send the level values to a central system in SAAS mode which will alert in the event of risk. Very flexible and simple, this solution adapts to all technical environments and can manage one to several hundred measurement points.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\" alt=\"\" width=\"298\" height=\"434\" \/><\/p>\n<p>The level sensors used are VEGAPULS type radars, either in a stand-alone version, or with a solar panel for extended autonomy, or in a wired version if a power supply is available. The VEGAPULS range of sensors offers a measuring range of up to more than 30m with a measurement error of less than 2mm. Thanks to their compactness, they easily integrate into the site environment (bridge pier or deck, gallows, wall). In addition, their discretion helps to preserve the aesthetics of the place and to avoid acts of vandalism.<\/p>\n<p>These radar wave measurements have multiple advantages such as excellent focusing as well as total insensitivity to weather conditions and contamination (spider webs or dead leaves) for optimal measurement reliability.<\/p>\n<p>\u00a0<\/p>\n<p>These sensors send data to a secure cloud through the LTE-M (4G) or LoRa network. It is a redundant architecture of two proprietary secure servers (SOC 2 and ISO\/IEC 27001). Accessible in real time around the world, either online or via a mobile application, the data can be retrieved via the VEGA VIS software, or transferred to the customer&#039;s information system via REST API. For example, they can be interfaced with a critical events management platform that can proactively notify the population by voice call, SMS, email, push on the call list in the event of a forecast of rising water levels.<\/p>\n<p>Thanks to VEGAPULS sensors and the VEGA VIS platform, flood management becomes simpler and more efficient, offering a proactive approach to dealing with these major natural risks. This system makes it possible to better prepare for floods, minimize their impacts and protect populations and infrastructure.<\/p>\n<p>Contact:<\/p>\n<p><strong>St\u00e9phanie MOUCHEL-<\/strong>Marketing Expert<\/p>\n<p>VEGA Technique SAS<br \/>15, rue du Ried<br \/>BP 20018 \u2013 Nordhouse<br \/>67151 Erstein Cedex \u2013 France<\/p>\n<p>Such. : +33 3 88 59 01 89<br \/>E-mail : <a href=\"mailto:stephanie.mouchel@vega.com\">stephanie.mouchel@vega.com<\/a><\/p>\n<p>web: <a href=\"http:\/\/www.vega.com\/\">www.vega.com<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>As the number one natural risk in France, flooding affects all regions. To anticipate flood risks, intermunicipalities as well as private sector players such as manufacturers and campsites seek to equip themselves with forecasting systems that complement state services. This is where VEGA provides\u2026<\/p>","protected":false},"author":349,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20427","post","type-post","status-publish","format-standard","hentry","category-defaut"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.<\/title>\n<meta name=\"description\" content=\"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reseau-mesure.com\/en\/vega-capteurs-prevision-des-crues\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.\" \/>\n<meta property=\"og:description\" content=\"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reseau-mesure.com\/en\/vega-capteurs-prevision-des-crues\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau Mesure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/reseaumesure\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-25T11:50:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-25T11:55:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\" \/>\n<meta name=\"author\" content=\"Claire Onfray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:site\" content=\"@ReseauMesure\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claire Onfray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/\"},\"author\":{\"name\":\"Claire Onfray\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/007ab9dfe1368385ff2e9d190ad34081\"},\"headline\":\"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.\",\"datePublished\":\"2023-09-25T11:50:39+00:00\",\"dateModified\":\"2023-09-25T11:55:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\",\"articleSection\":[\"Defaut\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/\",\"name\":\"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\",\"datePublished\":\"2023-09-25T11:50:39+00:00\",\"dateModified\":\"2023-09-25T11:55:05+00:00\",\"description\":\"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/vega-capteurs-prevision-des-crues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"name\":\"R\u00e9seau-Mesure\",\"description\":\"R\u00e9seau Mesure\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reseau-mesure.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#organization\",\"name\":\"R\u00e9seau-Mesure\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"contentUrl\":\"https:\\\/\\\/www.reseau-mesure.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/logo-max.png\",\"width\":545,\"height\":285,\"caption\":\"R\u00e9seau-Mesure\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/reseaumesure\\\/\",\"https:\\\/\\\/x.com\\\/ReseauMesure\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reseau-mesure\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.reseau-mesure.com\\\/#\\\/schema\\\/person\\\/007ab9dfe1368385ff2e9d190ad34081\",\"name\":\"Claire Onfray\",\"sameAs\":[\"https:\\\/\\\/www.reseau-mesure.com\"],\"url\":\"https:\\\/\\\/www.reseau-mesure.com\\\/en\\\/author\\\/confrayreseau-mesure-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VEGA is developing a secure cloud and radar level sensor solution for flood forecasting.","description":"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reseau-mesure.com\/en\/vega-capteurs-prevision-des-crues\/","og_locale":"en_US","og_type":"article","og_title":"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.","og_description":"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.","og_url":"https:\/\/www.reseau-mesure.com\/en\/vega-capteurs-prevision-des-crues\/","og_site_name":"R\u00e9seau Mesure","article_publisher":"https:\/\/www.facebook.com\/reseaumesure\/","article_published_time":"2023-09-25T11:50:39+00:00","article_modified_time":"2023-09-25T11:55:05+00:00","og_image":[{"url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg","type":"","width":"","height":""}],"author":"Claire Onfray","twitter_card":"summary_large_image","twitter_creator":"@ReseauMesure","twitter_site":"@ReseauMesure","twitter_misc":{"Written by":"Claire Onfray","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#article","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/"},"author":{"name":"Claire Onfray","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/007ab9dfe1368385ff2e9d190ad34081"},"headline":"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues.","datePublished":"2023-09-25T11:50:39+00:00","dateModified":"2023-09-25T11:55:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/"},"wordCount":481,"publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg","articleSection":["Defaut"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/","url":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/","name":"VEGA is developing a secure cloud and radar level sensor solution for flood forecasting.","isPartOf":{"@id":"https:\/\/www.reseau-mesure.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#primaryimage"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg","datePublished":"2023-09-25T11:50:39+00:00","dateModified":"2023-09-25T11:55:05+00:00","description":"VEGA apporte une solution innovante. De capteurs qui envoient les valeurs de niveau \u00e0 un syst\u00e8me central en mode SAAS.","breadcrumb":{"@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#primaryimage","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2023\/09\/AD-Radar-besser-als-Ultraschall_PULS31_160x2405mm-FR-Messehinweis-Pollutec-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reseau-mesure.com\/vega-capteurs-prevision-des-crues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.reseau-mesure.com\/"},{"@type":"ListItem","position":2,"name":"VEGA d\u00e9veloppe une solution \u00e0 capteurs de niveau radar et cloud s\u00e9curis\u00e9 pour la pr\u00e9vision de crues."}]},{"@type":"WebSite","@id":"https:\/\/www.reseau-mesure.com\/#website","url":"https:\/\/www.reseau-mesure.com\/","name":"R\u00e9seau-Mesure","description":"Network Measure","publisher":{"@id":"https:\/\/www.reseau-mesure.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reseau-mesure.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.reseau-mesure.com\/#organization","name":"R\u00e9seau-Mesure","url":"https:\/\/www.reseau-mesure.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","contentUrl":"https:\/\/www.reseau-mesure.com\/wp-content\/uploads\/2018\/02\/logo-max.png","width":545,"height":285,"caption":"R\u00e9seau-Mesure"},"image":{"@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/reseaumesure\/","https:\/\/x.com\/ReseauMesure","https:\/\/www.linkedin.com\/company\/reseau-mesure\/"]},{"@type":"Person","@id":"https:\/\/www.reseau-mesure.com\/#\/schema\/person\/007ab9dfe1368385ff2e9d190ad34081","name":"Claire Onfray","sameAs":["https:\/\/www.reseau-mesure.com"],"url":"https:\/\/www.reseau-mesure.com\/en\/author\/confrayreseau-mesure-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/posts\/20427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/comments?post=20427"}],"version-history":[{"count":0,"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/posts\/20427\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/media?parent=20427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/categories?post=20427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reseau-mesure.com\/en\/wp-json\/wp\/v2\/tags?post=20427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}